{"id":20001972,"date":"2024-04-19T14:22:53","date_gmt":"2024-04-19T14:22:53","guid":{"rendered":"https:\/\/nalouart.com\/privacy-policy\/"},"modified":"2024-06-16T09:38:03","modified_gmt":"2024-06-16T09:38:03","slug":"politique-confidentialite","status":"publish","type":"page","link":"https:\/\/nalouart.com\/fr\/politique-confidentialite\/","title":{"rendered":"Politique de Confidentialit\u00e9"},"content":{"rendered":"\r\n<h2 class=\"wp-block-heading\">Quem somos<\/h2>\r\n\r\n\r\n\r\n<p><strong class=\"privacy-policy-tutorial\">Texto sugerido: <\/strong>O endere\u00e7o do nosso site \u00e9: https:\/\/nalouart.com.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Coment\u00e1rios<\/h2>\r\n\r\n\r\n\r\n<p><strong class=\"privacy-policy-tutorial\">Texto sugerido: <\/strong>Quando os visitantes deixam coment\u00e1rios no site, s\u00e3o guardados os dados presentes no formul\u00e1rio dos coment\u00e1rios, bem como o endere\u00e7o de IP e o agente do utilizador do navegador, para ajudar com a detec\u00e7\u00e3o de spam.<\/p>\r\n\r\n\r\n\r\n<p>Uma string an\u00f3nima criada a partir do seu endere\u00e7o de email (tamb\u00e9m designada por hash) pode ser enviada para o servi\u00e7o Gravatar para verificar se o est\u00e1 a utilizar. A pol\u00edtica de privacidade do servi\u00e7o Gravatar est\u00e1 dispon\u00edvel aqui: https:\/\/automattic.com\/privacy\/. Depois do seu coment\u00e1rio ser aprovado, a fotografia do ser perfil fica vis\u00edvel para o p\u00fablico no contexto do seu coment\u00e1rio.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Multim\u00e9dia<\/h2>\r\n\r\n\r\n\r\n<p><strong class=\"privacy-policy-tutorial\">Texto sugerido: <\/strong>Ao carregar imagens para o site, deve evitar carregar imagens com dados incorporados de geolocaliza\u00e7\u00e3o (EXIF GPS). Os visitantes podem descarregar e extrair os dados de geolocaliza\u00e7\u00e3o das imagens do site.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Cookies<\/h2>\r\n\r\n\r\n\r\n<p><strong class=\"privacy-policy-tutorial\">Texto sugerido: <\/strong>Se deixar um coment\u00e1rio no nosso site pode optar por guardar o seu nome, endere\u00e7o de email e site nos cookies. Isto \u00e9 para sua conveni\u00eancia para n\u00e3o ter de preencher novamente os seus dados quando deixar outro coment\u00e1rio. Estes cookies durar\u00e3o um ano.<\/p>\r\n\r\n\r\n\r\n<p>Se visitar a p\u00e1gina de in\u00edcio de sess\u00e3o, ser\u00e1 configurado um cookie tempor\u00e1rio para determinar se o seu navegador aceita cookies. Este cookie n\u00e3o cont\u00e9m dados pessoais e ser\u00e1 eliminado ao fechar o seu navegador.<\/p>\r\n\r\n\r\n\r\n<p>Ao iniciar a sess\u00e3o, ser\u00e3o configurados alguns cookies para guardar a sua informa\u00e7\u00e3o de sess\u00e3o e as suas escolhas de visualiza\u00e7\u00e3o de ecr\u00e3. Os cookies de in\u00edcio de sess\u00e3o duram um ano. Se seleccionar \u00ab\u00a0Lembrar-me\u00a0\u00bb, a sua sess\u00e3o ir\u00e1 persistir durante duas semanas. Ao terminar a sess\u00e3o, os cookies de inicio de sess\u00e3o ser\u00e3o removidos.<\/p>\r\n\r\n\r\n\r\n<p>Se editar ou publicar um artigo, ser\u00e1 guardado no seu navegador um cookie adicional. Este cookie n\u00e3o inclui dados pessoais apenas indica o ID de conte\u00fado do artigo que acabou de editar. Expira ao fim de 1 dia.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Conte\u00fado incorporado de outros sites<\/h2>\r\n\r\n\r\n\r\n<p><strong class=\"privacy-policy-tutorial\">Texto sugerido: <\/strong>Os artigos neste site podem incluir conte\u00fado incorporado (por exemplo: v\u00eddeos, imagens, artigos, etc.). O conte\u00fado incorporado de outros sites comporta-se tal como se o utilizador visitasse esses sites.<\/p>\r\n\r\n\r\n\r\n<p>Este site pode recolher dados sobre si, usar cookies, incorporar rastreio feito por terceiros, monitorizar as suas interac\u00e7\u00f5es com o mesmo, incluindo registar as interac\u00e7\u00f5es com conte\u00fado incorporado se tiver uma conta e estiver com sess\u00e3o iniciada nesse site.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Com quem s\u00e3o partilhados os seus dados<\/h2>\r\n\r\n\r\n\r\n<p><strong class=\"privacy-policy-tutorial\">Texto sugerido: <\/strong>Se solicitar uma redefini\u00e7\u00e3o de senha, o seu endere\u00e7o de IP ser\u00e1 inclu\u00eddo no email de redefini\u00e7\u00e3o.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Por quanto tempo s\u00e3o retidos os seus dados<\/h2>\r\n\r\n\r\n\r\n<p><strong class=\"privacy-policy-tutorial\">Texto sugerido: <\/strong>Se deixar um coment\u00e1rio, o coment\u00e1rio e os seus metadados s\u00e3o guardados indefinidamente. Isto acontece de modo a ser poss\u00edvel reconhecer e aprovar automaticamente quaisquer coment\u00e1rios seguintes, em vez de os colocar numa fila de modera\u00e7\u00e3o.<\/p>\r\n\r\n\r\n\r\n<p>Para utilizadores que se registem no nosso site (se algum), guardamos a informa\u00e7\u00e3o pessoal fornecida no seu perfil de utilizador. Todos os utilizadores podem ver, editar, ou eliminar a sua informa\u00e7\u00e3o pessoal a qualquer momento (com a excep\u00e7\u00e3o de n\u00e3o poderem alterar o nome de utilizador). Os administradores do site podem tamb\u00e9m ver e editar essa informa\u00e7\u00e3o.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Que direitos tem sobre os seus dados<\/h2>\r\n\r\n\r\n\r\n<p><strong class=\"privacy-policy-tutorial\">Texto sugerido: <\/strong>Se tiver uma conta neste site, ou deixou coment\u00e1rios, pode pedir para receber um ficheiro de exporta\u00e7\u00e3o com os dados pessoais guardados sobre si, incluindo qualquer dado pessoal que indicou. Tamb\u00e9m pode solicitar que os dados guardados sejam eliminados. Isto n\u00e3o inclui qualquer dado pessoal que seja obrigat\u00f3rio manter para fins administrativos, legais ou de seguran\u00e7a.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Para onde os seus dados s\u00e3o enviados<\/h2>\r\n\r\n\r\n\r\n<p><strong class=\"privacy-policy-tutorial\">Texto sugerido: <\/strong>Os coment\u00e1rios dos visitantes podem ser verificados atrav\u00e9s de um servi\u00e7o autom\u00e1tico de detec\u00e7\u00e3o de spam.<\/p>\r\n\r\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Quem somos Texto sugerido: O endere\u00e7o do nosso site \u00e9: https:\/\/nalouart.com. Coment\u00e1rios Texto sugerido: Quando os visitantes deixam coment\u00e1rios no site, s\u00e3o guardados os dados presentes no formul\u00e1rio dos coment\u00e1rios, bem como o endere\u00e7o de IP e o agente do utilizador do navegador, para ajudar com a detec\u00e7\u00e3o de spam. Uma string an\u00f3nima criada a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-20001972","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/nalouart.com\/fr\/wp-json\/wp\/v2\/pages\/20001972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nalouart.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nalouart.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nalouart.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nalouart.com\/fr\/wp-json\/wp\/v2\/comments?post=20001972"}],"version-history":[{"count":8,"href":"https:\/\/nalouart.com\/fr\/wp-json\/wp\/v2\/pages\/20001972\/revisions"}],"predecessor-version":[{"id":20002298,"href":"https:\/\/nalouart.com\/fr\/wp-json\/wp\/v2\/pages\/20001972\/revisions\/20002298"}],"wp:attachment":[{"href":"https:\/\/nalouart.com\/fr\/wp-json\/wp\/v2\/media?parent=20001972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}